{"id":4464,"date":"2018-08-29T14:41:25","date_gmt":"2018-08-29T13:41:25","guid":{"rendered":"http:\/\/content.profilmedecin.fr\/?p=4464"},"modified":"2025-09-08T13:56:47","modified_gmt":"2025-09-08T12:56:47","slug":"les-solutions-qui-revolutionneront-bientot-votre-metier","status":"publish","type":"post","link":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/","title":{"rendered":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier"},"content":{"rendered":"<p><em>Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet derniers. Palmar\u00e8s, cat\u00e9gorie par cat\u00e9gorie. <\/em><\/p>\n<p>Chaque ann\u00e9e, entrepreneurs, professionnels de sant\u00e9, chercheurs, \u00e9tudiants ou encore, repr\u00e9sentants d\u2019associations de patients et d\u2019aidants sont invit\u00e9s \u00e0 pr\u00e9senter leurs innovations dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9*. En 2018, 153 projets ont \u00e9t\u00e9 d\u00e9pos\u00e9s. Parmi eux, une dizaine ont retenu l\u2019attention du jury.<\/p>\n<h2><strong>Cat\u00e9gorie \u00ab sant\u00e9 mobile &#8211; patient\/grand public \u00bb <\/strong><\/h2>\n<p><strong>Deepsen<\/strong> utilise la r\u00e9alit\u00e9 virtuelle pour soulager l&rsquo;anxi\u00e9t\u00e9 et la douleur. \u00ab <em>Inspir\u00e9es des techniques de la sophrologie, les s\u00e9ances th\u00e9rapeutiques propos\u00e9es par Deepsen offrent une alternative efficace \u00e0 la prise de m\u00e9dicaments et aux actes invasifs<\/em> \u00bb, assurent les fabricants install\u00e9s en r\u00e9gion Rh\u00f4ne Alpes.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"http:\/\/www.deepsen.io\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.deepsen.io\/<\/a><\/p>\n<h2><strong>Cat\u00e9gorie \u00ab sant\u00e9 mobile &#8211; professionnel de sant\u00e9 \u00bb <\/strong><\/h2>\n<p>De son c\u00f4t\u00e9, <strong>ScientiFeet<\/strong>, qui \u00e9quipe aujourd&rsquo;hui plus de 200 podologues en France, optimise le traitement des pathologies les plus courantes affectant les pieds. Elle r\u00e9pond aussi \u00ab <em>aux besoins de sportifs internationaux ou des patients diab\u00e9tiques<\/em> \u00bb.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"https:\/\/www.scientifeet.com\/?gclid=EAIaIQobChMIjMTszbaU3QIVzpPtCh188w96EAAYASAAEgL9h_D_BwE\" target=\"_blank\" rel=\"noopener\">https:\/\/www.scientifeet.com<\/a><\/p>\n<h2><strong>Cat\u00e9gorie \u00ab intelligence artificielle &amp; big data \u00bb <\/strong><\/h2>\n<p>C\u00f4t\u00e9 patients, la solution <strong>Lucine <\/strong>\u00ab <em>analyse, mesure et soulage la douleur \u00e0 domicile<\/em> \u00bb. C\u00f4t\u00e9 professionnels de sant\u00e9, \u00ab <em>elle optimise et accompagne le suivi<\/em> \u00bb. Et ce, pour une prise en charge \u00ab personnalis\u00e9e, s\u00e9curis\u00e9e et adapt\u00e9e \u00bb.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"http:\/\/mylittlesante.com\/lucine-la-esante-anti-douleur\/\" target=\"_blank\" rel=\"noopener\">http:\/\/mylittlesante.com\/lucine-la-esante-anti-douleur\/<\/a><\/p>\n<h2><strong>Cat\u00e9gorie \u00ab autonomie\/maintien \u00e0 domicile \u00bb <\/strong><\/h2>\n<p><strong>Cross brain<\/strong> propose aux patients souffrant de d\u00e9ficits cognitifs des \u00ab environnements d&rsquo;entra\u00eenement en r\u00e9alit\u00e9 virtuelle \u00bb pour les aider \u00e0 retrouver leur autonomie \u00ab <em>de fa\u00e7on efficace, motivante et s\u00e9curis\u00e9e<\/em> \u00bb.<\/p>\n<h2><strong>Cat\u00e9gorie \u00ab serious game sant\u00e9 \u00bb<\/strong><\/h2>\n<p>Le logiciel <strong>Covirtua Cognition<\/strong> recourt \u00e0 la r\u00e9alit\u00e9 virtuelle pour plonger les personnes victimes d\u2019AVC, de traumatisme cr\u00e2nien ou de maladie neurod\u00e9g\u00e9n\u00e9rative dans des situations de la vie quotidienne tout en \u00e9tant accompagn\u00e9es par leurs th\u00e9rapeutes.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"https:\/\/www.covirtua.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.covirtua.com\/<\/a><\/p>\n<h2><strong>Cat\u00e9gorie \u00ab t\u00e9l\u00e9m\u00e9decine \u00bb<\/strong><\/h2>\n<p>Deux solutions ont ainsi \u00e9t\u00e9 distingu\u00e9es dans la cat\u00e9gorie \u00ab t\u00e9l\u00e9m\u00e9decine \u00bb. La premi\u00e8re, <strong>Doctrin<\/strong>, est une plateforme cr\u00e9\u00e9e pour aider les professionnels de sant\u00e9 \u00e0 \u00ab <em>hi\u00e9rarchiser, traiter et suivre les patients, en toute s\u00e9curit\u00e9 et en ligne <\/em>\u00bb, pr\u00e9cisent ses concepteurs su\u00e9dois.<\/p>\n<p><strong>Deuxiemeavis.fr<\/strong>, lui, est un service qui permet aux patients confront\u00e9s \u00e0 un probl\u00e8me de sant\u00e9 grave d\u2019obtenir un deuxi\u00e8me avis m\u00e9dical \u00ab <em>en moins de sept jours aupr\u00e8s de m\u00e9decins qui ont un tr\u00e8s haut niveau d\u2019expertise sur leur maladie<\/em> \u00bb, d\u00e9taillent ses cr\u00e9ateurs parisiens.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"https:\/\/www.deuxiemeavis.fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.deuxiemeavis.fr\/<\/a><\/p>\n<h2><strong>Cat\u00e9gorie \u00ab coordination des soins \u00bb <\/strong><\/h2>\n<p>La plateforme de t\u00e9l\u00e9-expertise <strong>Postelo <\/strong>\u00ab <em>connecte tous les acteurs du soin<\/em> \u00bb (m\u00e9decins, infirmiers, structures\u2026) en leur permettant de communiquer au sujet de leurs patients.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0https:\/\/www.postelo.fr\/<\/p>\n<h2><strong>Cat\u00e9gorie \u00ab objets connect\u00e9s de sant\u00e9 \u00bb <\/strong><\/h2>\n<p>La solution <strong>Meersens<\/strong> permet \u00e0 chacun de tester son environnement imm\u00e9diat (qualit\u00e9 d&rsquo;air, qualit\u00e9 de l&rsquo;eau, UV, ondes, pesticides, allerg\u00e8nes&#8230;) quand il est susceptible de comporter un risque pour la sant\u00e9.<\/p>\n<p>Pour plus d&rsquo;informations :\u00a0<a href=\"https:\/\/meersens.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/meersens.com\/<\/a><\/p>\n<h2><strong>Autres Prix<\/strong><\/h2>\n<p>Enfin, quatre autres r\u00e9compenses ont \u00e9t\u00e9 attribu\u00e9es. L\u2019une, dans la cat\u00e9gorie \u00ab e-sant\u00e9 animale \u00bb, a salu\u00e9 la solution de visio-consultation et t\u00e9l\u00e9m\u00e9decine v\u00e9t\u00e9rinaire Linky Vet. Les autres, le \u00ab Grand Prix Pierre Fabre \u00bb, le \u00ab Prix des internautes \u00bb et le \u00ab Coup de c\u0153ur du jury \u00bb, ont r\u00e9compens\u00e9 des solutions de e-sant\u00e9 destin\u00e9es \u00e0 la prise en charge de patients atteints de scl\u00e9rose en plaques, de troubles du spectre de l\u2019autisme ou encore des femmes enceintes.<\/p>\n<p>Pour les d\u00e9couvrir, cliquez <a href=\"https:\/\/www.universite-esante.com\/\" target=\"_blank\" rel=\"noopener\">ici.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet derniers. Palmar\u00e8s, cat\u00e9gorie par cat\u00e9gorie. Chaque ann\u00e9e, entrepreneurs, professionnels de sant\u00e9, chercheurs, \u00e9tudiants ou encore, repr\u00e9sentants d\u2019associations de patients et d\u2019aidants sont invit\u00e9s \u00e0 pr\u00e9senter leurs innovations dans le&#8230; <a class=\"view-article\" href=\"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/\">Voir l&rsquo;article<\/a>","protected":false},"author":1,"featured_media":4465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[50,37,11],"class_list":["post-4464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-actualite","tag-interet","tag-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin<\/title>\n<meta name=\"description\" content=\"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin\" \/>\n<meta property=\"og:description\" content=\"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/\" \/>\n<meta property=\"og:site_name\" content=\"Profil M\u00e9decin\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-29T13:41:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T12:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1046\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_pm\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_pm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/\"},\"author\":{\"name\":\"admin_pm\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/person\\\/5881b8d3286f0a0c66bc562a78a8ef03\"},\"headline\":\"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier\",\"datePublished\":\"2018-08-29T13:41:25+00:00\",\"dateModified\":\"2025-09-08T12:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/trophees2018.png\",\"keywords\":[\"Actualit\u00e9\",\"int\u00e9r\u00eat\",\"sant\u00e9\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/\",\"name\":\"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/trophees2018.png\",\"datePublished\":\"2018-08-29T13:41:25+00:00\",\"dateModified\":\"2025-09-08T12:56:47+00:00\",\"description\":\"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/trophees2018.png\",\"contentUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/trophees2018.png\",\"width\":1046,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/les-solutions-qui-revolutionneront-bientot-votre-metier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#website\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\",\"name\":\"Profil M\u00e9decin\",\"description\":\"S\u00e9lection d&#039;opportunit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\",\"name\":\"Profil M\u00e9decin\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-profil-medecin.png\",\"contentUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-profil-medecin.png\",\"width\":325,\"height\":95,\"caption\":\"Profil M\u00e9decin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/person\\\/5881b8d3286f0a0c66bc562a78a8ef03\",\"name\":\"admin_pm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"caption\":\"admin_pm\"},\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin","description":"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/","og_locale":"fr_FR","og_type":"article","og_title":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin","og_description":"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet","og_url":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/","og_site_name":"Profil M\u00e9decin","article_published_time":"2018-08-29T13:41:25+00:00","article_modified_time":"2025-09-08T12:56:47+00:00","og_image":[{"width":1046,"height":423,"url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png","type":"image\/png"}],"author":"admin_pm","twitter_misc":{"\u00c9crit par":"admin_pm","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#article","isPartOf":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/"},"author":{"name":"admin_pm","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/person\/5881b8d3286f0a0c66bc562a78a8ef03"},"headline":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier","datePublished":"2018-08-29T13:41:25+00:00","dateModified":"2025-09-08T12:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/"},"wordCount":661,"publisher":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#primaryimage"},"thumbnailUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png","keywords":["Actualit\u00e9","int\u00e9r\u00eat","sant\u00e9"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/","url":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/","name":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier | Profil M\u00e9decin","isPartOf":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#primaryimage"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#primaryimage"},"thumbnailUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png","datePublished":"2018-08-29T13:41:25+00:00","dateModified":"2025-09-08T12:56:47+00:00","description":"Une dizaine de solutions de e-sant\u00e9 ont \u00e9t\u00e9 r\u00e9compens\u00e9es dans le cadre du concours international des Troph\u00e9es de la e-sant\u00e9 2018, les 4 et 5 juillet","breadcrumb":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#primaryimage","url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png","contentUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2018\/08\/trophees2018.png","width":1046,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/www.profilmedecin.fr\/contenu\/les-solutions-qui-revolutionneront-bientot-votre-metier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.profilmedecin.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Les solutions qui r\u00e9volutionneront bient\u00f4t votre m\u00e9tier"}]},{"@type":"WebSite","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#website","url":"https:\/\/www.profilmedecin.fr\/contenu\/","name":"Profil M\u00e9decin","description":"S\u00e9lection d&#039;opportunit\u00e9s","publisher":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.profilmedecin.fr\/contenu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization","name":"Profil M\u00e9decin","url":"https:\/\/www.profilmedecin.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2019\/11\/logo-profil-medecin.png","contentUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2019\/11\/logo-profil-medecin.png","width":325,"height":95,"caption":"Profil M\u00e9decin"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/person\/5881b8d3286f0a0c66bc562a78a8ef03","name":"admin_pm","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","caption":"admin_pm"},"url":"https:\/\/www.profilmedecin.fr\/contenu\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/4464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/comments?post=4464"}],"version-history":[{"count":5,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/4464\/revisions"}],"predecessor-version":[{"id":6893,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/4464\/revisions\/6893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/media\/4465"}],"wp:attachment":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/media?parent=4464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/categories?post=4464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/tags?post=4464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}