{"id":5397,"date":"2020-03-19T11:52:43","date_gmt":"2020-03-19T10:52:43","guid":{"rendered":"http:\/\/content.profilmedecin.fr\/?p=5397"},"modified":"2024-02-09T12:29:27","modified_gmt":"2024-02-09T11:29:27","slug":"covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients","status":"publish","type":"post","link":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/","title":{"rendered":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients"},"content":{"rendered":"<p><em>Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et d\u2019information \u00e0 l\u2019intention des m\u00e9decins lib\u00e9raux. Ces diff\u00e9rents supports doivent aider \u00e0 la prise en charge en ville des patients pr\u00e9sentant une forme simple ou mod\u00e9r\u00e9e du virus. Si ces outils sont probablement amen\u00e9s \u00e0 \u00e9voluer au fil des jours en fonction de la situation, en voici un aper\u00e7u \u00e0 date :<\/em><\/p>\n<p>Le Minist\u00e8re de la Sant\u00e9 a diffus\u00e9, le 16 mars, un <strong>guide m\u00e9thodologique de \u00ab pr\u00e9paration \u00e0 la phase \u00e9pid\u00e9mique de Covid-19 \u00bb<\/strong>. Il s\u2019adresse aux \u00e9tablissements de sant\u00e9 et aux \u00e9tablissements et services m\u00e9dico-sociaux mais \u00e9galement \u00e0 la m\u00e9decine de ville, revenant sur le r\u00f4le et l\u2019organisation de chacun.<br \/>\n<strong>Consulter le guide <a href=\"https:\/\/solidarites-sante.gouv.fr\/IMG\/pdf\/guide-covid-19-phase-epidemique-v15-16032020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">en cliquant ici\u00a0<\/a><\/strong><\/p>\n<p>Divers autres outils sont disponibles sur le site du Minist\u00e8re parmi lesquels une <strong>fiche pratique<\/strong> \u00e0 l\u2019intention des m\u00e9decins, un arbre d\u00e9cisionnel simplifi\u00e9, d\u00e9crivant la marche \u00e0 suivre \u00e9tape par \u00e9tape (selon les sympt\u00f4mes, le profil du patient, les r\u00e9sultats du test etc.) ou encore un outil de formation de masse \u00e0 destination des professionnels \u00e9labor\u00e9 par l\u2019EHESP compos\u00e9 de \u00ab capsules vid\u00e9o \u00bb et enrichi progressivement. Il convient de diffuser largement cet outil de formation.<br \/>\n<strong>Consulter la fiche m\u00e9decin <a href=\"https:\/\/solidarites-sante.gouv.fr\/IMG\/pdf\/covid-19_fiche_medecin_v16032020finalise.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">en cliquant ici<\/a>\u00a0<\/strong><br \/>\n<strong>Consulter l\u2019arbre d\u00e9cisionnel <a href=\"https:\/\/solidarites-sante.gouv.fr\/IMG\/pdf\/arbre-simplifie-pec-patient-covid-19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">en cliquant ici<\/a> <\/strong><\/p>\n<p>La liste de diffusion <strong>\u00ab\u00a0DGS-urgent\u00a0\u00bb<\/strong>\u00a0permet aux professionnels de sant\u00e9 de recevoir automatiquement des messages les avertissant de probl\u00e8mes sanitaires urgents par exemple des \u00e9pid\u00e9mies de m\u00e9ningite ou le signalement de produits dangereux. Pour b\u00e9n\u00e9ficier de ce service, il suffit de s&rsquo;inscrire.<br \/>\n<strong>S\u2019inscrire \u00e0 la liste DGS-Urgent <a href=\"https:\/\/dgs-urgent.sante.gouv.fr\/dgsurgent\/inter\/accueilBuilder.do?cmd=affiche\" target=\"_blank\" rel=\"noopener noreferrer\">en cliquant ici<\/a>\u00a0<\/strong><\/p>\n<p>Le Coll\u00e8ge de la M\u00e9decine g\u00e9n\u00e9rale (CMG) rassemble sur la plateforme <strong>Coronaclic<\/strong> toutes les informations \u2013 officielles et \u00e0 jour \u2013 utiles et n\u00e9cessaires aux m\u00e9decins g\u00e9n\u00e9ralistes : infographies sur la prise en charge et sur l\u2019organisation du cabinet, r\u00e9pertoire de r\u00e9f\u00e9rences, recommandations, textes officiels\u2026 Il est \u00e9galement possible d\u2019y poser ses questions.<br \/>\n<strong>Acc\u00e9der \u00e0 la plateforme ici\u00a0<\/strong><\/p>\n<p>Autre outil \u00e9labor\u00e9 par le CMG avec le Coll\u00e8ge CNGE et la SPILF (Soci\u00e9t\u00e9 de pathologie infectieuse de langue fran\u00e7aise), <strong>Antibioclic<\/strong>. Sur la base d\u2019un questionnaire \u00e0 remplir, cet algorithme simplifi\u00e9 des recommandations li\u00e9es au Covid-19 permet de voir la strat\u00e9gie th\u00e9rapeutique adapt\u00e9e \u00e0 adopter.<br \/>\n<strong>Acc\u00e9der au questionnaire<a href=\"https:\/\/antibioclic.com\/questionnaire\/57\" target=\"_blank\" rel=\"noopener noreferrer\"> ici<\/a>\u00a0<\/strong><\/p>\n<p>La <strong>t\u00e9l\u00e9consultation<\/strong> est \u00e0 privil\u00e9gier autant que faire se peut et en fonction des situations. Un d\u00e9cret a d\u2019ailleurs, publi\u00e9 le 10 mars, en adapte les modalit\u00e9s afin de faciliter la prise en charge des actes de t\u00e9l\u00e9m\u00e9decine pour les personnes expos\u00e9es au Covid-19 : ces derniers (infect\u00e9s ou pr\u00e9sentant des sympt\u00f4mes) ne sont plus oblig\u00e9s de passer par leur m\u00e9decin traitant pour r\u00e9aliser une t\u00e9l\u00e9consultation rembours\u00e9e par l&rsquo;Assurance maladie. Par ailleurs, ils ne seront plus contraints d\u2019avoir r\u00e9alis\u00e9 une consultation en pr\u00e9sentiel avec leur m\u00e9decin au cours des 12 derniers mois avant d&rsquo;obtenir un rendez-vous en t\u00e9l\u00e9consultation. Enfin, ces actes pourront \u00eatre r\u00e9alis\u00e9es \u00ab\u00a0<em>en utilisant n&rsquo;importe lequel des moyens technologiques actuellement disponibles pour r\u00e9aliser une vid\u00e9otransmission (lieu d\u00e9di\u00e9 \u00e9quip\u00e9 mais aussi site ou application s\u00e9curis\u00e9e via un ordinateur, une tablette ou un smartphone, \u00e9quip\u00e9 d&rsquo;une webcam et reli\u00e9 \u00e0 internet)\u00a0\u00bb<\/em>.<br \/>\n<strong>Se rapprocher de l\u2019ARS pour conna\u00eetre les dispositifs mis en place.<\/strong><\/p>\n<p><strong>\u00c0 noter :<\/strong> De mani\u00e8re g\u00e9n\u00e9rale, les sites et rubriques d\u00e9di\u00e9s du minist\u00e8re et des agences sont r\u00e9guli\u00e8rement mis \u00e0 jour. N\u2019h\u00e9sitez pas \u00e0 les consulter r\u00e9guli\u00e8rement :<br \/>\n\u00ab <strong><a href=\"https:\/\/solidarites-sante.gouv.fr\/soins-et-maladies\/maladies\/maladies-infectieuses\/coronavirus\/coronavirus-PS\" target=\"_blank\" rel=\"noopener noreferrer\">Coronavirus : informations aux professionnels de sant\u00e9<\/a> <\/strong>\u00bb du Minist\u00e8re de la Sant\u00e9 est r\u00e9guli\u00e8rement mise \u00e0 jour et augment\u00e9e.<br \/>\n<a href=\"https:\/\/www.santepubliquefrance.fr\/maladies-et-traumatismes\/maladies-et-infections-respiratoires\/infection-a-coronavirus\/articles\/infection-au-nouveau-coronavirus-sars-cov-2-covid-19-france-et-monde\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sant\u00e9 Publique France<\/strong><\/a><\/p>\n<blockquote><p><strong>Covid-19 : la CARMF vient en aide aux m\u00e9decins lib\u00e9raux<\/strong><\/p>\n<p>La Caisse Autonome de retraite des M\u00e9decins de France vient d\u2019annoncer la mise en place automatique et g\u00e9n\u00e9rale de la suspension du pr\u00e9l\u00e8vement mensuel de d\u00e9but avril ; la suspension des majorations de retard ; la suspension des rappels de cotisations de d\u00e9but d\u2019ann\u00e9e impay\u00e9es ; la suspension des mesures de recouvrement forc\u00e9 pendant une dur\u00e9e minimum de deux mois.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et d\u2019information \u00e0 l\u2019intention des m\u00e9decins lib\u00e9raux. Ces diff\u00e9rents supports doivent aider \u00e0 la prise en charge en ville des patients pr\u00e9sentant une forme simple ou mod\u00e9r\u00e9e du virus. Si ces&#8230; <a class=\"view-article\" href=\"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/\">Voir l&rsquo;article<\/a>","protected":false},"author":1,"featured_media":5407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[124,121,123,21,122],"class_list":["post-5397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-coronavirus","tag-covid-19","tag-fiche-pratique","tag-medecins","tag-outils"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin<\/title>\n<meta name=\"description\" content=\"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin\" \/>\n<meta property=\"og:description\" content=\"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/\" \/>\n<meta property=\"og:site_name\" content=\"Profil M\u00e9decin\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-19T10:52:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T11:29:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"857\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_pm\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_pm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/\"},\"author\":{\"name\":\"admin_pm\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/person\\\/5881b8d3286f0a0c66bc562a78a8ef03\"},\"headline\":\"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients\",\"datePublished\":\"2020-03-19T10:52:43+00:00\",\"dateModified\":\"2024-02-09T11:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/\"},\"wordCount\":753,\"publisher\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/humaniser-1.jpg\",\"keywords\":[\"coronavirus\",\"covid 19\",\"fiche pratique\",\"M\u00e9decins\",\"outils\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/\",\"name\":\"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/humaniser-1.jpg\",\"datePublished\":\"2020-03-19T10:52:43+00:00\",\"dateModified\":\"2024-02-09T11:29:27+00:00\",\"description\":\"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#primaryimage\",\"url\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/humaniser-1.jpg\",\"contentUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/humaniser-1.jpg\",\"width\":857,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#website\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\",\"name\":\"Profil M\u00e9decin\",\"description\":\"S\u00e9lection d&#039;opportunit\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#organization\",\"name\":\"Profil M\u00e9decin\",\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-profil-medecin.png\",\"contentUrl\":\"https:\\\/\\\/content.profilmedecin.fr\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-profil-medecin.png\",\"width\":325,\"height\":95,\"caption\":\"Profil M\u00e9decin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/#\\\/schema\\\/person\\\/5881b8d3286f0a0c66bc562a78a8ef03\",\"name\":\"admin_pm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g\",\"caption\":\"admin_pm\"},\"url\":\"https:\\\/\\\/www.profilmedecin.fr\\\/contenu\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin","description":"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/","og_locale":"fr_FR","og_type":"article","og_title":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin","og_description":"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et","og_url":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/","og_site_name":"Profil M\u00e9decin","article_published_time":"2020-03-19T10:52:43+00:00","article_modified_time":"2024-02-09T11:29:27+00:00","og_image":[{"width":857,"height":396,"url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg","type":"image\/jpeg"}],"author":"admin_pm","twitter_misc":{"\u00c9crit par":"admin_pm","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#article","isPartOf":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/"},"author":{"name":"admin_pm","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/person\/5881b8d3286f0a0c66bc562a78a8ef03"},"headline":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients","datePublished":"2020-03-19T10:52:43+00:00","dateModified":"2024-02-09T11:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/"},"wordCount":753,"publisher":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#primaryimage"},"thumbnailUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg","keywords":["coronavirus","covid 19","fiche pratique","M\u00e9decins","outils"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/","url":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/","name":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients | Profil M\u00e9decin","isPartOf":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#primaryimage"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#primaryimage"},"thumbnailUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg","datePublished":"2020-03-19T10:52:43+00:00","dateModified":"2024-02-09T11:29:27+00:00","description":"Suite au confinement mis en place pour limiter la propagation du Covid-19, le Minist\u00e8re et les agences de Sant\u00e9 ont \u00e9labor\u00e9 divers outils d\u2019aide et","breadcrumb":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#primaryimage","url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg","contentUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2020\/03\/humaniser-1.jpg","width":857,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/www.profilmedecin.fr\/contenu\/covid-19-divers-outils-mis-a-disposition-des-medecins-pour-la-prise-en-charge-des-patients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.profilmedecin.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Covid-19 : divers outils mis \u00e0 disposition des m\u00e9decins pour la prise en charge des patients"}]},{"@type":"WebSite","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#website","url":"https:\/\/www.profilmedecin.fr\/contenu\/","name":"Profil M\u00e9decin","description":"S\u00e9lection d&#039;opportunit\u00e9s","publisher":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.profilmedecin.fr\/contenu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#organization","name":"Profil M\u00e9decin","url":"https:\/\/www.profilmedecin.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2019\/11\/logo-profil-medecin.png","contentUrl":"https:\/\/content.profilmedecin.fr\/wp-content\/uploads\/2019\/11\/logo-profil-medecin.png","width":325,"height":95,"caption":"Profil M\u00e9decin"},"image":{"@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.profilmedecin.fr\/contenu\/#\/schema\/person\/5881b8d3286f0a0c66bc562a78a8ef03","name":"admin_pm","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8ec2dddc642dad64770ca106052024c5a9ad07b2f38988bda25f4df93f39bb8?s=96&d=mm&r=g","caption":"admin_pm"},"url":"https:\/\/www.profilmedecin.fr\/contenu\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/5397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/comments?post=5397"}],"version-history":[{"count":6,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/5397\/revisions"}],"predecessor-version":[{"id":6565,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/posts\/5397\/revisions\/6565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/media\/5407"}],"wp:attachment":[{"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/media?parent=5397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/categories?post=5397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.profilmedecin.fr\/contenu\/wp-json\/wp\/v2\/tags?post=5397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}